{"id":847,"count":2,"description":"","link":"https:\/\/designerreplica.io\/ar\/product-category\/brunello-cucinelli-sunglasses\/","name":"\u0628\u0631\u0648\u0646\u064a\u0644\u0644\u0648 \u0643\u0648\u062a\u0634\u064a\u0646\u064a\u0644\u0644\u064a","slug":"brunello-cucinelli-sunglasses","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/designerreplica.io\/ar\/wp-json\/wp\/v2\/product_cat\/847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designerreplica.io\/ar\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/designerreplica.io\/ar\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/designerreplica.io\/ar\/wp-json\/wp\/v2\/product?product_cat=847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}