{"id":170055,"date":"2026-08-22T22:04:58","date_gmt":"2026-08-22T22:04:58","guid":{"rendered":"https:\/\/designerreplica.io\/product\/loafer-imovel-em-preto-vl068\/"},"modified":"2026-08-31T21:37:22","modified_gmt":"2026-08-31T21:37:22","slug":"loafer-imovel-em-preto-vl068","status":"publish","type":"product","link":"https:\/\/designerreplica.io\/pt-br\/product\/loafer-imovel-em-preto-vl068\/","title":{"rendered":"LOAFER IM\u00d3VEL EM PRETO \u2013 VL068"},"content":{"rendered":"<p><strong>LOAFER IM\u00d3VEL EM PRETO&#8211;VL068<\/strong><\/p>\n<p>O Louis Vuitton Loafer and Drive \u00e9 o ep\u00edtome da eleg\u00e2ncia e do luxo atemporais. Fabricados com aten\u00e7\u00e3o meticulosa aos detalhes, estes sapatos combinam perfeitamente o design cl\u00e1ssico com a sofistica\u00e7\u00e3o moderna. Cada par exala sofistica\u00e7\u00e3o, ostentando materiais premium e acabamento impec\u00e1vel. Incorporando a ess\u00eancia da alta costura, s\u00e3o s\u00edmbolo de sofistica\u00e7\u00e3o e excelente qualidade.<\/p>\n<p>#LouisVuitton #LV #luxuryfashion #mocassins #LoaferandDrive #designershoes<\/p>\n<p>Replicacollects oferece alta qualidade<strong>Louis Vuitton Mocassim e Drive<\/strong>ao melhor pre\u00e7o do mercado. Entregamos produtos online em todo o mundo.<\/p>\n<p>Contacte-nos agora para aconselhamento em:<strong><a href=\"mailto:replicacollects@gmail.com\">replicacollects@gmail.com<\/a><\/strong><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>APENAS VENDA POR ATACADO &#8211; SEM VAREJO PARA USU\u00c1RIOS FINAIS<br \/>\u2022 Lote pequeno&amp;pedidos em grandes quantidades mistos aceitos<br \/>\u2022 Amostras dispon\u00edveis para inspe\u00e7\u00e3o de qualidade<br \/>\u2022 Pre\u00e7o unit\u00e1rio: US$ 20-200, o pre\u00e7o varia de acordo com o volume do pedido<br \/>\u2022 Entre em contato conosco via WhatsApp ou chat online para obter um or\u00e7amento exato&amp;Quantidade m\u00ednima.<\/p>\n","protected":false},"featured_media":18876,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bst_post_transparent":"","_bst_post_title":"","_bst_post_layout":"","_bst_post_sidebar_id":"","_bst_post_content_style":"","_bst_post_vertical_padding":"","_bst_post_feature":"","_bst_post_feature_position":"","_bst_post_header":false,"_bst_post_footer":false},"product_brand":[],"product_cat":[1647],"product_tag":[],"product_brands":[],"class_list":["post-170055","product","type-product","status-publish","has-post-thumbnail","product_cat-louis-vuitton-loafers-drivers","first","instock","shipping-taxable","product-type-simple","entry","content-bg","loop-entry"],"_links":{"self":[{"href":"https:\/\/designerreplica.io\/pt-br\/wp-json\/wp\/v2\/product\/170055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designerreplica.io\/pt-br\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/designerreplica.io\/pt-br\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/designerreplica.io\/pt-br\/wp-json\/wp\/v2\/comments?post=170055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/designerreplica.io\/pt-br\/wp-json\/wp\/v2\/media\/18876"}],"wp:attachment":[{"href":"https:\/\/designerreplica.io\/pt-br\/wp-json\/wp\/v2\/media?parent=170055"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/designerreplica.io\/pt-br\/wp-json\/wp\/v2\/product_brand?post=170055"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/designerreplica.io\/pt-br\/wp-json\/wp\/v2\/product_cat?post=170055"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/designerreplica.io\/pt-br\/wp-json\/wp\/v2\/product_tag?post=170055"},{"taxonomy":"product_brands","embeddable":true,"href":"https:\/\/designerreplica.io\/pt-br\/wp-json\/wp\/v2\/product_brands?post=170055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}